{"id":527,"date":"2010-10-26T08:34:06","date_gmt":"2010-10-26T12:34:06","guid":{"rendered":"http:\/\/www.dramaction.qc.ca\/fr\/?p=527"},"modified":"2010-10-26T08:34:06","modified_gmt":"2010-10-26T12:34:06","slug":"les-elements","status":"publish","type":"post","link":"https:\/\/www.dramaction.qc.ca\/fr\/les-elements\/","title":{"rendered":"Les \u00e9l\u00e9ments"},"content":{"rendered":"<p>AIR\u00a0: Alors que vous   vous d\u00e9placez dans l\u2019espace,  vous sentez votre corps s\u2019all\u00e9ger et devenir   l\u2019\u00e9l\u00e9ment air. Vous  pouvez explorer les sons qui vont avec cet \u00e9l\u00e9ment. Apportez   des  changements de rythme dans vos d\u00e9placements, arr\u00eats etc\u2026<\/p>\n<p>Improvisation en   groupe\u00a0: th\u00e8me: une tornade <strong>(5 minutes de pr\u00e9pa)<\/strong><\/p>\n<p>EAU\u00a0: Alors que vous   vous  d\u00e9placez dans l\u2019espace, votre corps va se remplir de l\u2019\u00e9l\u00e9ment eau et  petit   \u00e0 petit vous transformer en eau. Explorer cet \u00e9l\u00e9ments sous  toutes ses formes\u00a0:   goute \u00e0 goute, pluie, rivi\u00e8re, mer, cascades, lac.<\/p>\n<p>Impro par deux :   choisissez  l\u2019eau sous une de ses formes et faites en une pr\u00e9sentation. Essayez   de  donner \u00e0 cet eau le plus de d\u00e9tail, sa temp\u00e9rature, sa quantit\u00e9 (ex:  une   bouteille d&#8217;eau gazeuse).<strong> (5 minutes de pr\u00e9pa )<\/strong><\/p>\n<p>Impro en groupe\u00a0: Faire   la mer <strong>(5 minutes de pr\u00e9pa )<\/strong><\/p>\n<p>FEU\u00a0: R\u00e9partissez vous   dans  l\u2019espace et de l\u2019immobilit\u00e9 laissez na\u00eetre dans votre corps la chaleur  du   feu. Puis laissez vous envahir par cet \u00e9l\u00e9ments jusqu\u2019\u00e0 devenir  vous-m\u00eame un   feu, cr\u00e9pitant, irradiant, \u00e9blouissant<strong>\u2026<\/strong><\/p>\n<p>Solo\u00a0: Chacun son tour,   montrez nous un feu depuis sa prise jusqu\u2019\u00e0 son \u00e9touffement. (seulement les   volontaires)<\/p>\n<p>Impro de groupe\u00a0: Un   incendit.<strong> (5 minutes de pr\u00e9pa)<\/strong><\/p>\n<p>TERRE\u00a0: Vous \u00eates   r\u00e9parties  tous immobile dans l\u2019espace. Vous allez essayer de bouger mais votre    corps sera comme de la terre de poterie, de l\u2019argile. Cela demande un  grand   effort pour effectuer le moindre mouvement et tout le corps doit  s\u2019investir.   Attention de ne pas mettre trop de tension musculaire.  Essayez de trouver la   sensation de r\u00e9sistance et d\u2019effort sans bloquer  la respiration mais au   contraire en \u00e9tant dans un mouvement \u00e0 la fois  lent, fort et continu.<\/p>\n<p>Par deux\u00a0: Cr\u00e9er une   image de  statue, celle-ci n\u2019est pas encore tout \u00e0 fait s\u00e8che et les deux statues    vont essayer dans un dernier effort, d\u2019\u00e9chapper \u00e0 leur condition de  statues   avant de s\u2019immobiliser dans une derni\u00e8re position. \u00a0<strong>(5 minutes   de pr\u00e9pa )<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>AIR\u00a0: Alors que vous vous d\u00e9placez dans l\u2019espace, vous sentez votre corps s\u2019all\u00e9ger et devenir l\u2019\u00e9l\u00e9ment air. Vous pouvez explorer les sons qui vont avec cet \u00e9l\u00e9ment. Apportez des changements de rythme dans vos d\u00e9placements, arr\u00eats etc\u2026 Improvisation en groupe\u00a0: th\u00e8me: une tornade (5 minutes de pr\u00e9pa) EAU\u00a0: Alors que vous vous d\u00e9placez dans l\u2019espace, [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[27,24,9,4],"tags":[],"class_list":["post-527","post","type-post","status-publish","format-standard","hentry","category-paroles","category-exercices-difficiles","category-improvisation","category-exercices"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.dramaction.qc.ca\/fr\/wp-json\/wp\/v2\/posts\/527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dramaction.qc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dramaction.qc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dramaction.qc.ca\/fr\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dramaction.qc.ca\/fr\/wp-json\/wp\/v2\/comments?post=527"}],"version-history":[{"count":0,"href":"https:\/\/www.dramaction.qc.ca\/fr\/wp-json\/wp\/v2\/posts\/527\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dramaction.qc.ca\/fr\/wp-json\/wp\/v2\/media?parent=527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dramaction.qc.ca\/fr\/wp-json\/wp\/v2\/categories?post=527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dramaction.qc.ca\/fr\/wp-json\/wp\/v2\/tags?post=527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}